{"id":22,"count":1,"description":"","link":"https:\/\/smkserijempol.edu.my\/portal\/category\/hem\/","name":"HEM","slug":"hem","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/smkserijempol.edu.my\/portal\/wp-json\/wp\/v2\/categories\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smkserijempol.edu.my\/portal\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/smkserijempol.edu.my\/portal\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/smkserijempol.edu.my\/portal\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}